{"id":329,"date":"2025-10-20T01:22:21","date_gmt":"2025-10-19T23:22:21","guid":{"rendered":"https:\/\/heatpumpswatch.org\/unveiling\/"},"modified":"2025-11-30T18:21:12","modified_gmt":"2025-11-30T17:21:12","slug":"unveiling","status":"publish","type":"post","link":"https:\/\/heatpumpswatch.org\/de\/unveiling\/","title":{"rendered":"Bekanntmachung"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">OFFIZIELLER START<\/h4>\n\n\n\n<p>Offizielle Erkl\u00e4rung des Gr\u00fcnders: Start von Heat Pumps Watch.<br>Heute ist der Europ\u00e4ische W\u00e4rmepumpentag \u2013 ein besonderer Anlass f\u00fcr unsere Branche.<\/p>\n\n\n\n<p>F\u00fcr mich ist er jedoch noch bedeutsamer, denn heute, nach zwei Jahren Vorbereitung, freue ich mich, den offiziellen Start von Heat Pumps Watch bekannt zu geben!<\/p>\n\n\n\n<p>Eine gemeinn\u00fctzige Organisation, die sich der Bereitstellung unabh\u00e4ngiger und klarer Informationen widmet.<\/p>\n\n\n\n<p>Nach zwei Jahrzehnten als Wissenschaftler, Manager und Dozent bin ich zutiefst \u00fcberzeugt: Das gr\u00f6\u00dfte Hindernis der W\u00e4rmewende ist nicht technischer Natur \u2013 es ist das Vertrauen.<\/p>\n\n\n\n<p>Heat Pumps Watch wurde gegr\u00fcndet, um diese L\u00fccke zu schlie\u00dfen.<\/p>\n\n\n\n<p>Wir verwandeln Wissenschaft in Klarheit und stellen unabh\u00e4ngige, evidenzbasierte Informationen bereit, damit Hausbesitzer:innen, Fachleute und politische Entscheidungstr\u00e4ger:innen fundierte und sichere Entscheidungen treffen k\u00f6nnen.<\/p>\n\n\n\n<p>Unsere Arbeit hat bereits begonnen!<\/p>\n\n\n\n<p>Unsere erste gro\u00dfe Initiative ist eine 18-teilige Serie: \u201eW\u00e4rmepumpen: Ihre brennenden Fragen, jetzt beantwortet.\u201c Wir ersetzen Spekulationen durch Fakten und behandeln zentrale Themen \u2013 von W\u00e4rmepumpen in Bestandsgeb\u00e4uden bis hin zur Integration von KI.<\/p>\n\n\n\n<p>Und heute, am Europ\u00e4ischen W\u00e4rmepumpentag, \u00f6ffnen wir unsere T\u00fcren f\u00fcr die \u00d6ffentlichkeit. Besuchen Sie unsere Website, um mehr zu erfahren, und folgen Sie Heat Pumps Watch, um die Fakten zu erhalten, die Sie brauchen.<\/p>\n\n\n\n<p>Gehen wir gemeinsam voran \u2013 indem wir Vertrauen aufbauen und die Transformation aktiv vorantreiben.<\/p>\n\n\n\n<p>Danke.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls poster=\"https:\/\/heatpumpswatch.org\/wp-content\/uploads\/2025\/10\/marek-photo.webp\" src=\"https:\/\/heatpumpswatch.org\/wp-content\/uploads\/2025\/10\/HPW-2-1080p30H.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Heat Pumps Watch nimmt am W\u00e4rmepumpentag seine T\u00e4tigkeit auf \u2013 als unabh\u00e4ngige Organisation, die Vertrauen in die Energiewende aufbaut, indem sie wissenschaftlich fundierte Fakten vermittelt.<\/p>\n","protected":false},"author":1,"featured_media":331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[],"class_list":["post-329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/posts\/329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/comments?post=329"}],"version-history":[{"count":0,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/posts\/329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/media\/331"}],"wp:attachment":[{"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/media?parent=329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/categories?post=329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heatpumpswatch.org\/de\/wp-json\/wp\/v2\/tags?post=329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}